{"id":479,"date":"2019-01-21T18:26:25","date_gmt":"2019-01-21T17:26:25","guid":{"rendered":"http:\/\/www.sinoskop.de\/blog\/?p=479"},"modified":"2026-04-01T21:44:13","modified_gmt":"2026-04-01T19:44:13","slug":"die-china-droge-scholz-sternstunden-in-peking","status":"publish","type":"post","link":"https:\/\/www.sinoskop.de\/blog\/die-china-droge-scholz-sternstunden-in-peking\/","title":{"rendered":"#7 Die \u201eChina-Droge&#8220; &#8211; Scholz&#8216; Sternstunden in Peking"},"content":{"rendered":"<p>Heute beginnt das Weltwirtschaftsforum in Davos, wo es in den n\u00e4chsten Tagen um den aktuellen Zustand der Weltwirtschaft und m\u00f6gliche Aussichten gehen wird. China wird sicherlich auch in den Schweizer Bergen ein zentrales Thema sein. Mehr dazu bald. Hier folgt zuerst ein selektiver R\u00fcckblick auf das, was letzte Woche wichtig war. Viel Vergn\u00fcgen.<\/p>\n<p><!--more--><\/p>\n<h2 style=\"text-align: center;\">\u00a0\u201eChina-Droge&#8220;: Deutsche Unternehmen zeigen erste Entzugserscheinungen<\/h2>\n<p>Einen \u00dcberblick zu den Verflechtungen deutscher Unternehmen im Reich der Mitte ver\u00f6ffentlichte das <em>Handelsblatt<\/em> zum vergangenen Wochenende. Der Leitartikel f\u00fchrt facettenreich vor Augen, wie stark die Abh\u00e4ngigkeit der deutschen Industrie vom chinesischen Wachstumsmarkt im Verlauf der vergangenen Jahrzehnte geworden ist. Der Fokus liegt oftmals schon l\u00e4ngst st\u00e4rker auf Fernost als auf dem heimischen europ\u00e4ischen Markt, wie Verkaufszahlen und Investitionen im Reich der Mitte belegen.<\/p>\n<p>Die \u201eChina-Droge&#8220; der Deutschland AG wird mit wirtschaftlichen Eckdaten veranschaulicht und so lassen die vergangenen Jahrzehnte sich durchaus als rauschende Erfolgsgeschichte lesen. Diese niemals endende Party ist jetzt scheinbar doch langsam vorbei und Katerstimmung macht sich breit. Denn die deutsche Wirtschaft ist \u201egefangen im China-Dilemma&#8220;.<\/p>\n<p>Den Artikel in voller L\u00e4nge gibt es hier.<\/p>\n<p><strong>Kommentar:<\/strong> Sp\u00e4testens seit dem Beitritt Chinas zur Welthandelsorganisation 2001 ging man von einer Art zwangsl\u00e4ufigen, fast schon naturgem\u00e4\u00dfen \u00d6ffnung des Landes nach westlichen Vorstellungen aus. In der neoliberalen Theorie beispielsweise f\u00fchrt wirtschaftliches Wachstum beinahe automatisch zu einer weiteren wirtschaftlichen und politischen \u00d6ffnung. Und als Bonuszugabe gibt es Freiheit und Demokratie oben drauf. Die Praxis sah und sieht oft anders aus. Jetzt also h\u00e4ngt die deutsche Wirtschaft am Tropf der &#8222;China-Droge&#8220;.<\/p>\n<p>F\u00fcr das chinesische Modell passen Theorien wie diese oder andere stets nur bedingt, da sich dessen einmalige Entwicklung w\u00e4hrend der letzten vier Jahrzehnte (<a href=\"https:\/\/www.sinoskop.de\/blog\/china-40-jahre-reform-und-oeffnung-eu-china-beziehungen\/#more-418\" target=\"_blank\" rel=\"noopener noreferrer\">siehe auch #4<\/a>) schwer mit vergangenem vergleichen l\u00e4sst. Zu gro\u00df und vielf\u00e4ltig ist das Land, zu gewaltig sind nach wie vor die Gegens\u00e4tze. Allem voran das Gef\u00e4lle zwischen urbanem und l\u00e4ndlichem Raum geh\u00f6rt mit zu den gr\u00f6\u00dften Herausforderungen der F\u00fchrung in Peking.<\/p>\n<p>Und das China-Dilemma der deutschen Wirtschaft? Hier darf bemerkt werden, dass die deutsche Industrie sich durchaus frei- und bereitwillig in diese sogenannte Gefangenschaft begeben hat. Und auch darf angemerkt werden, dass man sich w\u00e4hrend dieser jahrzehntelang anhaltenden Goldgr\u00e4berstimmung eher wenig f\u00fcr das Dilemma vieler Arbeiter und Fabrikangestellter vor Ort interessierte.<\/p>\n<p>Nicht wenige kritische Stimmen sehen in dem Verhalten der deutschen Industrie sowie staatlicher Politik China gegen\u00fcber gar als Ausverkauf des sch\u00f6nen Tafelsilbers und Deutschland als \u201eSchn\u00e4ppchenmarkt&#8220;.<\/p>\n<p>Die neue Aussenwirtschaftsverordnung zu Firmen\u00fcbernahmen, Grundsatzpapiere zum Umgang mit China, die geplante Fusion von Siemens und Alstom im Bahnbereich, der Mobilfunknetzausbau; im Licht der zuvor genannten Kritik lesen sich all diese Ma\u00dfnahmen als Versuche des Gegensteuerns Seitens der deutschen Politik und Wirtschaft (<a href=\"https:\/\/www.sinoskop.de\/blog\/6-usa-china-verhandlungen-kim-jong-un-feiert-in-peking-mondaufnahmen-bdi-grundsatzpapier\/#more-453\" target=\"_blank\" rel=\"noopener noreferrer\">siehe auch #6).<\/a><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"qyPtOASLGk\"><p><a href=\"https:\/\/www.sinoskop.de\/blog\/usa-china-verhandlungen-kim-jong-un-in-peking-mondaufnahmen-bdi-grundsatzpapier\/\">#6 BDI-Grundsatzpapier zu China\/US-Chinesischer Gespr\u00e4chsmarathon\/Kim Jong-Un feiert in Peking\/Chang&#8217;e sendet Bilder vom Mond<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;#6 BDI-Grundsatzpapier zu China\/US-Chinesischer Gespr\u00e4chsmarathon\/Kim Jong-Un feiert in Peking\/Chang&#8217;e sendet Bilder vom Mond&#8220; &#8212; S i n o s k o p\" src=\"https:\/\/www.sinoskop.de\/blog\/usa-china-verhandlungen-kim-jong-un-in-peking-mondaufnahmen-bdi-grundsatzpapier\/embed\/#?secret=PPrYuHJEXp#?secret=qyPtOASLGk\" data-secret=\"qyPtOASLGk\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>Das wahre Dilemma aber, findet Sinoskop, ist und bleibt ein \u00fcberholter Glaube an grenzenloses Wachstum, Konsum und Profitgier in einer Welt der begrenzten Ressourcen. Ob mit oder ohne &#8218;&#8220;China-Droge&#8220;.<\/p>\n<p><strong>Mehr dazu:<\/strong><\/p>\n<p>WIWO: <a href=\"https:\/\/www.wiwo.de\/unternehmen\/auto\/innovationen-neue-wege-statt-imitation-wie-chinas-autobauer-die-deutschen-ueberholen\/23873384.html\" target=\"_blank\" rel=\"noopener noreferrer\">Chinesische Autobauer haben die Nase vorn<\/a><\/p>\n<p>DRADIO: <a href=\"https:\/\/www.deutschlandfunk.de\/e-auto-trifft-internet-chinas-weg-zur-automobilspitze.724.de.html?dram:article_id=438192\" target=\"_blank\" rel=\"noopener noreferrer\">Auf dem Weg zur Automobilspitze<\/a><\/p>\n<p>WIWO: <a href=\"https:\/\/www.wiwo.de\/unternehmen\/it\/ermittlungen-druck-auf-chinas-telekom-riesen-huawei-waechst\/23876640.html\" target=\"_blank\" rel=\"noopener noreferrer\">Huawei weiter unter Druck<\/a><\/p>\n<p>SZ: <a href=\"https:\/\/www.sueddeutsche.de\/wirtschaft\/siemens-alstom-1.4293471\" target=\"_blank\" rel=\"noopener noreferrer\">Europa braucht die Zug-Fusion<\/a><\/p>\n<hr \/>\n<h2 style=\"text-align: center;\">Zweiter Deutsch-Chinesischer Finanzdialog<\/h2>\n<p>Zwar langsam nur, z\u00f6gerlich und ungeachtet des China-Dilemmas \u00f6ffnet sich nun doch, was f\u00fcr hiesige Unternehmen eine bisher unzug\u00e4ngliche Schatzttruhe war: Die chinesische Banken- und Versicherungsbranche.<\/p>\n<p>Um auf diesem Feld den Marktzugang zu sichern und sich m\u00f6glichst gewinnbringend aufgestellt zu sehen, reiste der deutsche Finanzminister und Vizekanzler in Begleitung von Bundesbank-Pr\u00e4sident Weidmann und Felix Hufeld, Chef der Bundesanstalt f\u00fcr Finanzdienstleistungsaufsicht (BaFin), zu einem zweit\u00e4gigen Dialog nach Peking.<\/p>\n<p>Im Aktenkoffer hatten die G\u00e4ste drei Abkommen, welche erfolgreich unterzeichnet wurden und zu<\/p>\n<ul>\n<li>einer Kooperation der Bankenaufsichten beider Staaten<\/li>\n<li>mehr Zusammenarbeit beim Wertpapierhandel<\/li>\n<li>einer st\u00e4rkeren Kooperation der Zentralbanken<\/li>\n<\/ul>\n<p>beitragen sollen.<\/p>\n<p><strong>Mehr dazu:<\/strong><\/p>\n<p>HB: <a href=\"https:\/\/www.handelsblatt.com\/politik\/deutschland\/marktzugang-scholz-macht-sich-in-china-fuer-deutsche-banken-und-versicherer-stark\/23876730.html?ticket=ST-1105393-4HrLx9Y4voSSrDre23ek-ap4\" target=\"_blank\" rel=\"noopener noreferrer\">Finanzminister Scholz reist nach China<\/a><\/p>\n<p>SZ: <a href=\"https:\/\/www.sueddeutsche.de\/politik\/scholz-china-bank-versicherung-1.4291410\" target=\"_blank\" rel=\"noopener noreferrer\">Ein Handlungsreisender in Peking<\/a><\/p>\n<p>SPON: <a href=\"http:\/\/www.spiegel.de\/wirtschaft\/soziales\/olaf-scholz-in-china-reden-wir-ueber-geld-a-1248463.html\" target=\"_blank\" rel=\"noopener noreferrer\">Scholz in Peking<\/a><\/p>\n<p>SZ: <a href=\"https:\/\/www.sueddeutsche.de\/politik\/scholz-peking-china-besuch-menschenrechte-1.4293469\" target=\"_blank\" rel=\"noopener noreferrer\">Keine Zeit f\u00fcr Menschenrechte<\/a><\/p>\n<hr \/>\n<h4 style=\"text-align: center;\">Sehens-\/Lesens-\/H\u00f6renswertes<\/h4>\n<p>ZEIT: <a href=\"https:\/\/www.zeit.de\/politik\/ausland\/2019-01\/militaer-us-geheimdienst-china-waffensystem-warnung-wachsende-kapazitaeten\" target=\"_blank\" rel=\"noopener noreferrer\">Chinas modernes Milit\u00e4r<\/a><\/p>\n<p>TAZ: <a href=\"https:\/\/www.taz.de\/Archiv-Suche\/!5561480&amp;s=europa%2Bmuss%2Bantworten\/\" target=\"_blank\" rel=\"noopener noreferrer\">Umweltschutz &#8211; Interview mit J\u00fcrgen Trittin<\/a><\/p>\n<p>FAZ: <a href=\"https:\/\/www.faz.net\/aktuell\/politik\/ausland\/todesurteil-gegen-kanadier-wachsende-spannungen-zwischen-china-und-kanada-15990045.html\" target=\"_blank\" rel=\"noopener noreferrer\">Hochspannung zwischen Kanada und China<\/a><\/p>\n<p>NZZ: <a href=\"https:\/\/www.nzz.ch\/feuilleton\/china-mao-ueber-fehler-sprechen-aber-keine-zugeben-ld.1451563\" target=\"_blank\" rel=\"noopener noreferrer\">Chinas Umgang mit der eigenen Vergangenheit<\/a><\/p>\n<p>WELT: <a href=\"https:\/\/www.welt.de\/kultur\/article187189624\/Genesis-2-0-Erst-lassen-wir-Mammuts-auferstehen-dann-erschaffen-wir-Menschen.html?wtrid=onsite.onsitesearch\" target=\"_blank\" rel=\"noopener noreferrer\">Kinofilm \u00fcber Gentechnik, China in einer Hauptrolle<\/a><\/p>\n<p>ARTE: E-Commerce erobert das Land<\/p>\n<p>ARD: (Weltspiegel) <a href=\"https:\/\/www.daserste.de\/information\/politik-weltgeschehen\/weltspiegel\/videos\/weltspiegel-kasachstan-china-video-100.html\" target=\"_blank\" rel=\"noopener noreferrer\">Zur Lage der Kasachen in China<\/a><\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Heute beginnt das Weltwirtschaftsforum in Davos, wo es in den n\u00e4chsten Tagen um den aktuellen Zustand der Weltwirtschaft und m\u00f6gliche Aussichten gehen wird. China wird sicherlich auch in den Schweizer <a class=\"mh-excerpt-more\" href=\"https:\/\/www.sinoskop.de\/blog\/die-china-droge-scholz-sternstunden-in-peking\/\" title=\"#7 Die \u201eChina-Droge&#8220; &#8211; Scholz&#8216; Sternstunden in Peking\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,24],"tags":[51,32,52,53],"class_list":["post-479","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-politik-wirtschaft","tag-davos","tag-deutsch-chinesisch","tag-deutsche-wirtschaft","tag-trump"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wirtschaft auf China-Droge\/Scholz in Peking- China im 21. Jhdt. betrachten<\/title>\n<meta name=\"description\" content=\"Die Deutsche Wirtschaft auf China-Droge; Finanzminister Scholz nimmt am zweiten Deutsch-Chinesischem Finanzdialog in Peking teil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sinoskop.de\/blog\/die-china-droge-scholz-sternstunden-in-peking\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wirtschaft auf China-Droge\/Scholz in Peking- China im 21. Jhdt. betrachten\" \/>\n<meta property=\"og:description\" content=\"Die Deutsche Wirtschaft auf China-Droge; Finanzminister Scholz nimmt am zweiten Deutsch-Chinesischem Finanzdialog in Peking teil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sinoskop.de\/blog\/die-china-droge-scholz-sternstunden-in-peking\/\" \/>\n<meta property=\"og:site_name\" content=\"China Blog Sinoskop\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-21T17:26:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T19:44:13+00:00\" \/>\n<meta name=\"author\" content=\"Matthias M.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sinoskop\" \/>\n<meta name=\"twitter:site\" content=\"@sinoskop\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matthias M.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/die-china-droge-scholz-sternstunden-in-peking\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/die-china-droge-scholz-sternstunden-in-peking\\\/\"},\"author\":{\"name\":\"Matthias M.\",\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/#\\\/schema\\\/person\\\/dbe836c6fc7202cdf3ecfb132a484a8a\"},\"headline\":\"#7 Die \u201eChina-Droge&#8220; &#8211; Scholz&#8216; Sternstunden in Peking\",\"datePublished\":\"2019-01-21T17:26:25+00:00\",\"dateModified\":\"2026-04-01T19:44:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/die-china-droge-scholz-sternstunden-in-peking\\\/\"},\"wordCount\":715,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/#\\\/schema\\\/person\\\/dbe836c6fc7202cdf3ecfb132a484a8a\"},\"keywords\":[\"Davos\",\"Deutsch-Chinesisch\",\"Deutsche Wirtschaft\",\"Trump\"],\"articleSection\":{\"1\":\"Politik &amp; Wirtschaft\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/die-china-droge-scholz-sternstunden-in-peking\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/die-china-droge-scholz-sternstunden-in-peking\\\/\",\"url\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/die-china-droge-scholz-sternstunden-in-peking\\\/\",\"name\":\"Wirtschaft auf China-Droge\\\/Scholz in Peking- China im 21. Jhdt. betrachten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/#website\"},\"datePublished\":\"2019-01-21T17:26:25+00:00\",\"dateModified\":\"2026-04-01T19:44:13+00:00\",\"description\":\"Die Deutsche Wirtschaft auf China-Droge; Finanzminister Scholz nimmt am zweiten Deutsch-Chinesischem Finanzdialog in Peking teil.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/die-china-droge-scholz-sternstunden-in-peking\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/die-china-droge-scholz-sternstunden-in-peking\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/die-china-droge-scholz-sternstunden-in-peking\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#7 Die \u201eChina-Droge&#8220; &#8211; Scholz&#8216; Sternstunden in Peking\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/\",\"name\":\"China Blog Sinoskop\",\"description\":\"China im 21. Jahrhundert betrachten\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/#\\\/schema\\\/person\\\/dbe836c6fc7202cdf3ecfb132a484a8a\"},\"alternateName\":\"Sinoskop\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/#\\\/schema\\\/person\\\/dbe836c6fc7202cdf3ecfb132a484a8a\",\"name\":\"Matthias M.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-cropped-IMG_0911-e1701450243917.jpeg\",\"url\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-cropped-IMG_0911-e1701450243917.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-cropped-IMG_0911-e1701450243917.jpeg\",\"width\":249,\"height\":83,\"caption\":\"Matthias M.\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-cropped-IMG_0911-e1701450243917.jpeg\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/sinoskop\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wirtschaft auf China-Droge\/Scholz in Peking- China im 21. Jhdt. betrachten","description":"Die Deutsche Wirtschaft auf China-Droge; Finanzminister Scholz nimmt am zweiten Deutsch-Chinesischem Finanzdialog in Peking teil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sinoskop.de\/blog\/die-china-droge-scholz-sternstunden-in-peking\/","og_locale":"de_DE","og_type":"article","og_title":"Wirtschaft auf China-Droge\/Scholz in Peking- China im 21. Jhdt. betrachten","og_description":"Die Deutsche Wirtschaft auf China-Droge; Finanzminister Scholz nimmt am zweiten Deutsch-Chinesischem Finanzdialog in Peking teil.","og_url":"https:\/\/www.sinoskop.de\/blog\/die-china-droge-scholz-sternstunden-in-peking\/","og_site_name":"China Blog Sinoskop","article_published_time":"2019-01-21T17:26:25+00:00","article_modified_time":"2026-04-01T19:44:13+00:00","author":"Matthias M.","twitter_card":"summary_large_image","twitter_creator":"@sinoskop","twitter_site":"@sinoskop","twitter_misc":{"Verfasst von":"Matthias M.","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sinoskop.de\/blog\/die-china-droge-scholz-sternstunden-in-peking\/#article","isPartOf":{"@id":"https:\/\/www.sinoskop.de\/blog\/die-china-droge-scholz-sternstunden-in-peking\/"},"author":{"name":"Matthias M.","@id":"https:\/\/www.sinoskop.de\/blog\/#\/schema\/person\/dbe836c6fc7202cdf3ecfb132a484a8a"},"headline":"#7 Die \u201eChina-Droge&#8220; &#8211; Scholz&#8216; Sternstunden in Peking","datePublished":"2019-01-21T17:26:25+00:00","dateModified":"2026-04-01T19:44:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sinoskop.de\/blog\/die-china-droge-scholz-sternstunden-in-peking\/"},"wordCount":715,"commentCount":0,"publisher":{"@id":"https:\/\/www.sinoskop.de\/blog\/#\/schema\/person\/dbe836c6fc7202cdf3ecfb132a484a8a"},"keywords":["Davos","Deutsch-Chinesisch","Deutsche Wirtschaft","Trump"],"articleSection":{"1":"Politik &amp; Wirtschaft"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sinoskop.de\/blog\/die-china-droge-scholz-sternstunden-in-peking\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sinoskop.de\/blog\/die-china-droge-scholz-sternstunden-in-peking\/","url":"https:\/\/www.sinoskop.de\/blog\/die-china-droge-scholz-sternstunden-in-peking\/","name":"Wirtschaft auf China-Droge\/Scholz in Peking- China im 21. Jhdt. betrachten","isPartOf":{"@id":"https:\/\/www.sinoskop.de\/blog\/#website"},"datePublished":"2019-01-21T17:26:25+00:00","dateModified":"2026-04-01T19:44:13+00:00","description":"Die Deutsche Wirtschaft auf China-Droge; Finanzminister Scholz nimmt am zweiten Deutsch-Chinesischem Finanzdialog in Peking teil.","breadcrumb":{"@id":"https:\/\/www.sinoskop.de\/blog\/die-china-droge-scholz-sternstunden-in-peking\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sinoskop.de\/blog\/die-china-droge-scholz-sternstunden-in-peking\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sinoskop.de\/blog\/die-china-droge-scholz-sternstunden-in-peking\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.sinoskop.de\/blog\/"},{"@type":"ListItem","position":2,"name":"#7 Die \u201eChina-Droge&#8220; &#8211; Scholz&#8216; Sternstunden in Peking"}]},{"@type":"WebSite","@id":"https:\/\/www.sinoskop.de\/blog\/#website","url":"https:\/\/www.sinoskop.de\/blog\/","name":"China Blog Sinoskop","description":"China im 21. Jahrhundert betrachten","publisher":{"@id":"https:\/\/www.sinoskop.de\/blog\/#\/schema\/person\/dbe836c6fc7202cdf3ecfb132a484a8a"},"alternateName":"Sinoskop","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sinoskop.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.sinoskop.de\/blog\/#\/schema\/person\/dbe836c6fc7202cdf3ecfb132a484a8a","name":"Matthias M.","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.sinoskop.de\/blog\/wp-content\/uploads\/2023\/12\/cropped-cropped-IMG_0911-e1701450243917.jpeg","url":"https:\/\/www.sinoskop.de\/blog\/wp-content\/uploads\/2023\/12\/cropped-cropped-IMG_0911-e1701450243917.jpeg","contentUrl":"https:\/\/www.sinoskop.de\/blog\/wp-content\/uploads\/2023\/12\/cropped-cropped-IMG_0911-e1701450243917.jpeg","width":249,"height":83,"caption":"Matthias M."},"logo":{"@id":"https:\/\/www.sinoskop.de\/blog\/wp-content\/uploads\/2023\/12\/cropped-cropped-IMG_0911-e1701450243917.jpeg"},"sameAs":["https:\/\/x.com\/sinoskop"]}]}},"_links":{"self":[{"href":"https:\/\/www.sinoskop.de\/blog\/wp-json\/wp\/v2\/posts\/479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sinoskop.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sinoskop.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sinoskop.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sinoskop.de\/blog\/wp-json\/wp\/v2\/comments?post=479"}],"version-history":[{"count":1,"href":"https:\/\/www.sinoskop.de\/blog\/wp-json\/wp\/v2\/posts\/479\/revisions"}],"predecessor-version":[{"id":8566,"href":"https:\/\/www.sinoskop.de\/blog\/wp-json\/wp\/v2\/posts\/479\/revisions\/8566"}],"wp:attachment":[{"href":"https:\/\/www.sinoskop.de\/blog\/wp-json\/wp\/v2\/media?parent=479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sinoskop.de\/blog\/wp-json\/wp\/v2\/categories?post=479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sinoskop.de\/blog\/wp-json\/wp\/v2\/tags?post=479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}