{"id":218,"count":1,"description":"","link":"https:\/\/www.sinoskop.de\/blog\/tag\/annalena-baerbock\/","name":"Annalena Baerbock","slug":"annalena-baerbock","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Annalena Baerbock Archive - China Blog Sinoskop China-Blog<\/title>\n<meta name=\"description\" content=\"Sinoskop - das Original: unabh\u00e4ngiger China-Blog auf Deutsch. Aktuelle Entwicklungen, Hintergr\u00fcnde, Medienfilter &amp; Analysen aus Politik, Wirtschaft, Umwelt &amp; Kultur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sinoskop.de\/blog\/tag\/annalena-baerbock\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Annalena Baerbock Archive - China Blog Sinoskop China-Blog\" \/>\n<meta property=\"og:description\" content=\"Sinoskop - das Original: unabh\u00e4ngiger China-Blog auf Deutsch. Aktuelle Entwicklungen, Hintergr\u00fcnde, Medienfilter &amp; Analysen aus Politik, Wirtschaft, Umwelt &amp; Kultur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sinoskop.de\/blog\/tag\/annalena-baerbock\/\" \/>\n<meta property=\"og:site_name\" content=\"China Blog Sinoskop\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@sinoskop\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/tag\\\/annalena-baerbock\\\/\",\"url\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/tag\\\/annalena-baerbock\\\/\",\"name\":\"Annalena Baerbock Archive - China Blog Sinoskop China-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/#website\"},\"description\":\"Sinoskop - das Original: unabh\u00e4ngiger China-Blog auf Deutsch. Aktuelle Entwicklungen, Hintergr\u00fcnde, Medienfilter & Analysen aus Politik, Wirtschaft, Umwelt & Kultur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/tag\\\/annalena-baerbock\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/tag\\\/annalena-baerbock\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Annalena Baerbock\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/\",\"name\":\"China Blog Sinoskop\",\"description\":\"China im 21. Jahrhundert betrachten\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/#\\\/schema\\\/person\\\/dbe836c6fc7202cdf3ecfb132a484a8a\"},\"alternateName\":\"Sinoskop\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/#\\\/schema\\\/person\\\/dbe836c6fc7202cdf3ecfb132a484a8a\",\"name\":\"Matthias M.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-cropped-IMG_0911-e1701450243917.jpeg\",\"url\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-cropped-IMG_0911-e1701450243917.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-cropped-IMG_0911-e1701450243917.jpeg\",\"width\":249,\"height\":83,\"caption\":\"Matthias M.\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.sinoskop.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-cropped-IMG_0911-e1701450243917.jpeg\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/sinoskop\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Annalena Baerbock Archive - China Blog Sinoskop China-Blog","description":"Sinoskop - das Original: unabh\u00e4ngiger China-Blog auf Deutsch. Aktuelle Entwicklungen, Hintergr\u00fcnde, Medienfilter & Analysen aus Politik, Wirtschaft, Umwelt & Kultur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sinoskop.de\/blog\/tag\/annalena-baerbock\/","og_locale":"de_DE","og_type":"article","og_title":"Annalena Baerbock Archive - China Blog Sinoskop China-Blog","og_description":"Sinoskop - das Original: unabh\u00e4ngiger China-Blog auf Deutsch. Aktuelle Entwicklungen, Hintergr\u00fcnde, Medienfilter & Analysen aus Politik, Wirtschaft, Umwelt & Kultur.","og_url":"https:\/\/www.sinoskop.de\/blog\/tag\/annalena-baerbock\/","og_site_name":"China Blog Sinoskop","twitter_card":"summary_large_image","twitter_site":"@sinoskop","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.sinoskop.de\/blog\/tag\/annalena-baerbock\/","url":"https:\/\/www.sinoskop.de\/blog\/tag\/annalena-baerbock\/","name":"Annalena Baerbock Archive - China Blog Sinoskop China-Blog","isPartOf":{"@id":"https:\/\/www.sinoskop.de\/blog\/#website"},"description":"Sinoskop - das Original: unabh\u00e4ngiger China-Blog auf Deutsch. Aktuelle Entwicklungen, Hintergr\u00fcnde, Medienfilter & Analysen aus Politik, Wirtschaft, Umwelt & Kultur.","breadcrumb":{"@id":"https:\/\/www.sinoskop.de\/blog\/tag\/annalena-baerbock\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sinoskop.de\/blog\/tag\/annalena-baerbock\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.sinoskop.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Annalena Baerbock"}]},{"@type":"WebSite","@id":"https:\/\/www.sinoskop.de\/blog\/#website","url":"https:\/\/www.sinoskop.de\/blog\/","name":"China Blog Sinoskop","description":"China im 21. Jahrhundert betrachten","publisher":{"@id":"https:\/\/www.sinoskop.de\/blog\/#\/schema\/person\/dbe836c6fc7202cdf3ecfb132a484a8a"},"alternateName":"Sinoskop","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sinoskop.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.sinoskop.de\/blog\/#\/schema\/person\/dbe836c6fc7202cdf3ecfb132a484a8a","name":"Matthias M.","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.sinoskop.de\/blog\/wp-content\/uploads\/2023\/12\/cropped-cropped-IMG_0911-e1701450243917.jpeg","url":"https:\/\/www.sinoskop.de\/blog\/wp-content\/uploads\/2023\/12\/cropped-cropped-IMG_0911-e1701450243917.jpeg","contentUrl":"https:\/\/www.sinoskop.de\/blog\/wp-content\/uploads\/2023\/12\/cropped-cropped-IMG_0911-e1701450243917.jpeg","width":249,"height":83,"caption":"Matthias M."},"logo":{"@id":"https:\/\/www.sinoskop.de\/blog\/wp-content\/uploads\/2023\/12\/cropped-cropped-IMG_0911-e1701450243917.jpeg"},"sameAs":["https:\/\/x.com\/sinoskop"]}]}},"_links":{"self":[{"href":"https:\/\/www.sinoskop.de\/blog\/wp-json\/wp\/v2\/tags\/218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sinoskop.de\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.sinoskop.de\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.sinoskop.de\/blog\/wp-json\/wp\/v2\/posts?tags=218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}